{"id":6638,"date":"2020-03-03T11:35:10","date_gmt":"2020-03-03T11:35:10","guid":{"rendered":"https:\/\/wirtznv.com\/construction-has-begun-at-south-dock-gardens-wood-wharf-uk\/"},"modified":"2024-05-22T16:57:34","modified_gmt":"2024-05-22T14:57:34","slug":"bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen","status":"publish","type":"post","link":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/","title":{"rendered":"Bauarbeiten in den South Dock Gardens, Wood Wharf (GB), haben begonnen"},"content":{"rendered":"<p>In\u202fLondons Canary Wharf entsteht ein neues Viertel, das nach seiner Fertigstellung bis zu 3.600 neue Wohnungen, eine zweiz\u00fcgige Grundschule, 490.000 Quadratmeter Einzelhandelsfl\u00e4che und acht Hektar \u00f6ffentliche R\u00e4ume, Pl\u00e4tze und \u00fcppige gr\u00fcne Parks umfasst. Es ist ein erstklassiger Ort, um die H\u00f6hepunkte des Lebens in einer der lebendigsten und aufregendsten Gegenden Londons zu genie\u00dfen.<\/p>\n<p>Durch ihre intensive Begr\u00fcnung werden die\u202f<a href=\"https:\/\/wirtznv.com\/de\/projekte\/oeffentliche-raum\/\">\u00f6ffentliche R\u00e4ume<\/a> und Parks\u202fin Wood Wharf zu Oasen der Frische und stehen in Kontrast zur Dichte der Stadt. Die South Dock Gardens in Wood Wharf sind dem Wind sehr ausgesetzt. Und zu allem \u00dcberfluss f\u00e4rbt sich das Wasser im South Dock im Winter ziemlich schwarz. Deshalb verwenden wir viele ausladende Formen von\u202fZiergr\u00e4sern und Stauden, die im Winter besonders sch\u00f6n aussehen. Auf diese Weise behalten die\u202f<a href=\"https:\/\/wirtznv.com\/de\/projekte\/oeffentliche-raum\/\">\u00d6ffentliche Raum<\/a>\u202fihre Lebendigkeit, auch wenn das Wetter umschl\u00e4gt.<\/p>\n<p>Die Fertigstellung dieses neuen Viertels in Londons Canary Wharf wird derzeit f\u00fcr 2023 erwartet. Klicken Sie\u202f<a href=\"https:\/\/woodwharf.com\/\">hier<\/a>, um weitere Informationen zu erhalten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In\u202fLondons Canary Wharf entsteht ein neues Viertel, das nach seiner Fertigstellung bis zu 3.600 neue Wohnungen, eine zweiz\u00fcgige Grundschule, 490.000 Quadratmeter Einzelhandelsfl\u00e4che und acht Hektar \u00f6ffentliche R\u00e4ume, Pl\u00e4tze und \u00fcppige gr\u00fcne Parks umfasst. Es ist ein erstklassiger Ort, um die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8132,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>South Dock Gardens | Wirtz International Landschaftsarchitekten<\/title>\n<meta name=\"description\" content=\"Die South Dock Gardens sind dem Wind sehr ausgesetzt. Und zu allem \u00dcberfluss f\u00e4rbt sich das Wasser im South Dock im Winter ziemlich schwarz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"South Dock Gardens | Wirtz International Landschaftsarchitekten\" \/>\n<meta property=\"og:description\" content=\"Die South Dock Gardens sind dem Wind sehr ausgesetzt. Und zu allem \u00dcberfluss f\u00e4rbt sich das Wasser im South Dock im Winter ziemlich schwarz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/\" \/>\n<meta property=\"og:site_name\" content=\"Wirtz NV\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-03T11:35:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-22T14:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wirtznv.com\/wp-content\/uploads\/2020\/03\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dxv_webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wirtz_Gardens\" \/>\n<meta name=\"twitter:site\" content=\"@Wirtz_Gardens\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"dxv_webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/\"},\"author\":{\"name\":\"dxv_webmaster\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#\\\/schema\\\/person\\\/238ae8b6d8292a0cce4aba73db1f4de7\"},\"headline\":\"Bauarbeiten in den South Dock Gardens, Wood Wharf (GB), haben begonnen\",\"datePublished\":\"2020-03-03T11:35:10+00:00\",\"dateModified\":\"2024-05-22T14:57:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/\"},\"wordCount\":180,\"publisher\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/\",\"name\":\"South Dock Gardens | Wirtz International Landschaftsarchitekten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg\",\"datePublished\":\"2020-03-03T11:35:10+00:00\",\"dateModified\":\"2024-05-22T14:57:34+00:00\",\"description\":\"Die South Dock Gardens sind dem Wind sehr ausgesetzt. Und zu allem \u00dcberfluss f\u00e4rbt sich das Wasser im South Dock im Winter ziemlich schwarz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg\",\"contentUrl\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg\",\"width\":1600,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bauarbeiten in den South Dock Gardens, Wood Wharf (GB), haben begonnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/\",\"name\":\"Wirtz NV\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#organization\",\"name\":\"Wirtz International Landscape Architects\",\"alternateName\":\"Wirtz NV\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo_header@2x-1.png\",\"contentUrl\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo_header@2x-1.png\",\"width\":177,\"height\":161,\"caption\":\"Wirtz International Landscape Architects\"},\"image\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Wirtz_Gardens\",\"https:\\\/\\\/www.instagram.com\\\/Wirtz_International\\\/\"],\"description\":\"Wirtz International Landscape Architects ist ein belgisches Garten- und Landschaftsarchitekturb\u00fcro in Schoten bei Antwerpen, gegr\u00fcndet von Jacques Wirtz. Das B\u00fcro entwirft Privatg\u00e4rten, Firmeng\u00e4rten, \u00f6ffentliche R\u00e4ume und Dachg\u00e4rten im In- und Ausland.\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Botermelkdijk 464\",\"addressLocality\":\"Schoten\",\"postalCode\":\"2900\",\"addressCountry\":\"BE\"},\"telephone\":\"+32 3 680 13 22\",\"email\":\"info@wirtznv.be\",\"founder\":{\"@type\":\"Person\",\"name\":\"Jacques Wirtz\",\"birthDate\":\"1924\",\"jobTitle\":\"Landscape architect\",\"description\":\"Belgisch tuin- en landschapsarchitect, geboren in Antwerpen in 1924, oprichter van het bureau.\"},\"knowsAbout\":[\"Landscape architecture\",\"Garden design\",\"Public space design\",\"Roof gardens\",\"Private gardens\"],\"areaServed\":[\"BE\",\"NL\",\"FR\",\"DE\",\"GB\",\"US\",\"ES\",\"CH\",\"PL\"],\"foundingDate\":\"1950\",\"employee\":[{\"@type\":\"Person\",\"name\":\"Martin Wirtz\",\"jobTitle\":\"Landscape architect\"},{\"@type\":\"Person\",\"name\":\"Peter Wirtz\",\"jobTitle\":\"Landscape architect\"}],\"location\":[{\"@type\":\"Place\",\"name\":\"Wirtz International Landscape Architects \u2014 Schoten\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Botermelkdijk 464\",\"addressLocality\":\"Schoten\",\"postalCode\":\"2900\",\"addressCountry\":\"BE\"},\"telephone\":\"+32 3 680 13 22\"},{\"@type\":\"Place\",\"name\":\"Wirtz International Landscape Architects \u2014 Hamburg\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Armgartstra\u00dfe 4\",\"addressLocality\":\"Hamburg\",\"postalCode\":\"22087\",\"addressCountry\":\"DE\"},\"telephone\":\"+49 40 226 30336\"},{\"@type\":\"Place\",\"name\":\"Wirtz International Landscape Architects \u2014 Glastonbury\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"100 Western Blvd\",\"addressLocality\":\"Glastonbury\",\"addressRegion\":\"CT\",\"postalCode\":\"06033\",\"addressCountry\":\"US\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#\\\/schema\\\/person\\\/238ae8b6d8292a0cce4aba73db1f4de7\",\"name\":\"dxv_webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g\",\"caption\":\"dxv_webmaster\"},\"sameAs\":[\"https:\\\/\\\/wirtznv.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"South Dock Gardens | Wirtz International Landschaftsarchitekten","description":"Die South Dock Gardens sind dem Wind sehr ausgesetzt. Und zu allem \u00dcberfluss f\u00e4rbt sich das Wasser im South Dock im Winter ziemlich schwarz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/","og_locale":"de_DE","og_type":"article","og_title":"South Dock Gardens | Wirtz International Landschaftsarchitekten","og_description":"Die South Dock Gardens sind dem Wind sehr ausgesetzt. Und zu allem \u00dcberfluss f\u00e4rbt sich das Wasser im South Dock im Winter ziemlich schwarz.","og_url":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/","og_site_name":"Wirtz NV","article_published_time":"2020-03-03T11:35:10+00:00","article_modified_time":"2024-05-22T14:57:34+00:00","og_image":[{"width":1600,"height":2000,"url":"https:\/\/wirtznv.com\/wp-content\/uploads\/2020\/03\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg","type":"image\/jpeg"}],"author":"dxv_webmaster","twitter_card":"summary_large_image","twitter_creator":"@Wirtz_Gardens","twitter_site":"@Wirtz_Gardens","twitter_misc":{"Verfasst von":"dxv_webmaster","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/#article","isPartOf":{"@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/"},"author":{"name":"dxv_webmaster","@id":"https:\/\/wirtznv.com\/de\/#\/schema\/person\/238ae8b6d8292a0cce4aba73db1f4de7"},"headline":"Bauarbeiten in den South Dock Gardens, Wood Wharf (GB), haben begonnen","datePublished":"2020-03-03T11:35:10+00:00","dateModified":"2024-05-22T14:57:34+00:00","mainEntityOfPage":{"@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/"},"wordCount":180,"publisher":{"@id":"https:\/\/wirtznv.com\/de\/#organization"},"image":{"@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/#primaryimage"},"thumbnailUrl":"https:\/\/wirtznv.com\/wp-content\/uploads\/2020\/03\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/","url":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/","name":"South Dock Gardens | Wirtz International Landschaftsarchitekten","isPartOf":{"@id":"https:\/\/wirtznv.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/#primaryimage"},"image":{"@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/#primaryimage"},"thumbnailUrl":"https:\/\/wirtznv.com\/wp-content\/uploads\/2020\/03\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg","datePublished":"2020-03-03T11:35:10+00:00","dateModified":"2024-05-22T14:57:34+00:00","description":"Die South Dock Gardens sind dem Wind sehr ausgesetzt. Und zu allem \u00dcberfluss f\u00e4rbt sich das Wasser im South Dock im Winter ziemlich schwarz.","breadcrumb":{"@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/#primaryimage","url":"https:\/\/wirtznv.com\/wp-content\/uploads\/2020\/03\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg","contentUrl":"https:\/\/wirtznv.com\/wp-content\/uploads\/2020\/03\/News-Construction-has-begun-at-South-dock-Gardens-Wood-Wharf-UK.jpg","width":1600,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/wirtznv.com\/de\/bauarbeiten-in-den-south-dock-gardens-wood-wharf-haben-begonnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wirtznv.com\/de\/"},{"@type":"ListItem","position":2,"name":"Bauarbeiten in den South Dock Gardens, Wood Wharf (GB), haben begonnen"}]},{"@type":"WebSite","@id":"https:\/\/wirtznv.com\/de\/#website","url":"https:\/\/wirtznv.com\/de\/","name":"Wirtz NV","description":"","publisher":{"@id":"https:\/\/wirtznv.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wirtznv.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wirtznv.com\/de\/#organization","name":"Wirtz International Landscape Architects","alternateName":"Wirtz NV","url":"https:\/\/wirtznv.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wirtznv.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wirtznv.com\/wp-content\/uploads\/2021\/03\/logo_header@2x-1.png","contentUrl":"https:\/\/wirtznv.com\/wp-content\/uploads\/2021\/03\/logo_header@2x-1.png","width":177,"height":161,"caption":"Wirtz International Landscape Architects"},"image":{"@id":"https:\/\/wirtznv.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Wirtz_Gardens","https:\/\/www.instagram.com\/Wirtz_International\/"],"description":"Wirtz International Landscape Architects ist ein belgisches Garten- und Landschaftsarchitekturb\u00fcro in Schoten bei Antwerpen, gegr\u00fcndet von Jacques Wirtz. Das B\u00fcro entwirft Privatg\u00e4rten, Firmeng\u00e4rten, \u00f6ffentliche R\u00e4ume und Dachg\u00e4rten im In- und Ausland.","address":{"@type":"PostalAddress","streetAddress":"Botermelkdijk 464","addressLocality":"Schoten","postalCode":"2900","addressCountry":"BE"},"telephone":"+32 3 680 13 22","email":"info@wirtznv.be","founder":{"@type":"Person","name":"Jacques Wirtz","birthDate":"1924","jobTitle":"Landscape architect","description":"Belgisch tuin- en landschapsarchitect, geboren in Antwerpen in 1924, oprichter van het bureau."},"knowsAbout":["Landscape architecture","Garden design","Public space design","Roof gardens","Private gardens"],"areaServed":["BE","NL","FR","DE","GB","US","ES","CH","PL"],"foundingDate":"1950","employee":[{"@type":"Person","name":"Martin Wirtz","jobTitle":"Landscape architect"},{"@type":"Person","name":"Peter Wirtz","jobTitle":"Landscape architect"}],"location":[{"@type":"Place","name":"Wirtz International Landscape Architects \u2014 Schoten","address":{"@type":"PostalAddress","streetAddress":"Botermelkdijk 464","addressLocality":"Schoten","postalCode":"2900","addressCountry":"BE"},"telephone":"+32 3 680 13 22"},{"@type":"Place","name":"Wirtz International Landscape Architects \u2014 Hamburg","address":{"@type":"PostalAddress","streetAddress":"Armgartstra\u00dfe 4","addressLocality":"Hamburg","postalCode":"22087","addressCountry":"DE"},"telephone":"+49 40 226 30336"},{"@type":"Place","name":"Wirtz International Landscape Architects \u2014 Glastonbury","address":{"@type":"PostalAddress","streetAddress":"100 Western Blvd","addressLocality":"Glastonbury","addressRegion":"CT","postalCode":"06033","addressCountry":"US"}}]},{"@type":"Person","@id":"https:\/\/wirtznv.com\/de\/#\/schema\/person\/238ae8b6d8292a0cce4aba73db1f4de7","name":"dxv_webmaster","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g","caption":"dxv_webmaster"},"sameAs":["https:\/\/wirtznv.com"]}]}},"_links":{"self":[{"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/posts\/6638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/comments?post=6638"}],"version-history":[{"count":0,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/posts\/6638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/media\/8132"}],"wp:attachment":[{"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/media?parent=6638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/categories?post=6638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/tags?post=6638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}