{"id":6041,"date":"2017-05-03T09:40:56","date_gmt":"2017-05-03T09:40:56","guid":{"rendered":"https:\/\/wirtznv.com\/chambon-in-brussels-wins-27th-mipim-award-for-best-refurbished-building\/"},"modified":"2024-05-28T14:44:13","modified_gmt":"2024-05-28T12:44:13","slug":"chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude","status":"publish","type":"post","link":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/","title":{"rendered":"Chambon in Br\u00fcssel gewinnt den 27. MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude"},"content":{"rendered":"<p>Die 27. MIPIM Awards wurden heute im Rahmen der MIPIM, der internationalen Messe f\u00fcr Wohn- und Gewerbeimmobilien, verliehen. Die Ergebnisse wurden im Rahmen einer Gala im Grand Auditorium des Palais des Festivals in Cannes bekannt gegeben. Europa war nahe dran, alle Troph\u00e4en zu gewinnen, mit Siegerprojekten aus Belgien, D\u00e4nemark, Deutschland, Frankreich, Gro\u00dfbritannien und Polen, die in 3 verschiedenen Kategorien ausgezeichnet wurden. Die von Reed MIDEM, einer Tochtergesellschaft von Reed Exhibitions, organisierte MIPIM findet derzeit in Cannes statt.<\/p>\n<p><strong>Chambon in Br\u00fcssel<\/strong>\u202fgewann den MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude. Es handelt sich um den gr\u00f6\u00dften Umbau von B\u00fcros in Br\u00fcssel und das gr\u00f6\u00dfte, gemischt genutzte Ensemble, das in den letzten vier Jahrzehnten gebaut wurde. Chambon wird aus einem 75.000 m\u00b2 gro\u00dfen, nur f\u00fcr B\u00fcrozwecke genutzten Geb\u00e4udekomplex ein lebendiges, 50.000 m\u00b2 gro\u00dfes, gemischt genutztes Ensemble aus erhaltenen und restaurierten historischen Geb\u00e4uden, renovierten und umgestalteten Geb\u00e4uden sowie neu errichteten Geb\u00e4uden machen. Auf dem Gel\u00e4nde befinden sich jetzt 248 Wohnungen, 134 Studentenstudios, B\u00fcros, ein F\u00fcnf-Sterne-Boutique-Hotel und ein easyHotel sowie ein Food-Court und Einzelhandelsgesch\u00e4fte. Die urspr\u00fcnglich vollst\u00e4ndig ebenerdig errichteten Geb\u00e4ude aus den 1970er und 1980er Jahren wurden abgerissen, um das Gel\u00e4nde um einen 3.000 m\u00b2 gro\u00dfen, von Wirtz International NV entworfenen Garten herum neu zu gestalten.<\/p>\n<p><a href=\"http:\/\/www.mipimawards.com\/mipimawards2017\/en\/page\/winners-2017\" target=\"_blank\" rel=\"noopener\">http:\/\/www.mipimawards.com\/mipimawards2017\/en\/page\/winners-2017<\/a><\/p>\n<p>Bauunternehmer: IMMOBEL<br \/>\nArchitekt: A2RC Architects \/ Jaspers-Eyers Architects<br \/>\nLandschaftsarchitekt: Wirtz International NV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die 27. MIPIM Awards wurden heute im Rahmen der MIPIM, der internationalen Messe f\u00fcr Wohn- und Gewerbeimmobilien, verliehen. Die Ergebnisse wurden im Rahmen einer Gala im Grand Auditorium des Palais des Festivals in Cannes bekannt gegeben. Europa war nahe dran, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8116,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chambon Br\u00fcssel | Wirtz International Gartenarchitekten<\/title>\n<meta name=\"description\" content=\"Chambon in Br\u00fcssel gewann den MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude. Es handelt sich um den gr\u00f6\u00dften Umbau von B\u00fcros in Br\u00fcssel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chambon Br\u00fcssel | Wirtz International Gartenarchitekten\" \/>\n<meta property=\"og:description\" content=\"Chambon in Br\u00fcssel gewann den MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude. Es handelt sich um den gr\u00f6\u00dften Umbau von B\u00fcros in Br\u00fcssel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/\" \/>\n<meta property=\"og:site_name\" content=\"Wirtz NV\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-03T09:40:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-28T12:44:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wirtznv.com\/wp-content\/uploads\/2017\/05\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dxv_webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wirtz_Gardens\" \/>\n<meta name=\"twitter:site\" content=\"@Wirtz_Gardens\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"dxv_webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/\"},\"author\":{\"name\":\"dxv_webmaster\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#\\\/schema\\\/person\\\/238ae8b6d8292a0cce4aba73db1f4de7\"},\"headline\":\"Chambon in Br\u00fcssel gewinnt den 27. MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude\",\"datePublished\":\"2017-05-03T09:40:56+00:00\",\"dateModified\":\"2024-05-28T12:44:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/\"},\"wordCount\":258,\"publisher\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/\",\"name\":\"Chambon Br\u00fcssel | Wirtz International Gartenarchitekten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg\",\"datePublished\":\"2017-05-03T09:40:56+00:00\",\"dateModified\":\"2024-05-28T12:44:13+00:00\",\"description\":\"Chambon in Br\u00fcssel gewann den MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude. Es handelt sich um den gr\u00f6\u00dften Umbau von B\u00fcros in Br\u00fcssel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg\",\"contentUrl\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg\",\"width\":2000,\"height\":1124},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chambon in Br\u00fcssel gewinnt den 27. MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/\",\"name\":\"Wirtz NV\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#organization\",\"name\":\"Wirtz International Landscape Architects\",\"alternateName\":\"Wirtz NV\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo_header@2x-1.png\",\"contentUrl\":\"https:\\\/\\\/wirtznv.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo_header@2x-1.png\",\"width\":177,\"height\":161,\"caption\":\"Wirtz International Landscape Architects\"},\"image\":{\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Wirtz_Gardens\",\"https:\\\/\\\/www.instagram.com\\\/Wirtz_International\\\/\"],\"description\":\"Wirtz International Landscape Architects ist ein belgisches Garten- und Landschaftsarchitekturb\u00fcro in Schoten bei Antwerpen, gegr\u00fcndet von Jacques Wirtz. Das B\u00fcro entwirft Privatg\u00e4rten, Firmeng\u00e4rten, \u00f6ffentliche R\u00e4ume und Dachg\u00e4rten im In- und Ausland.\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Botermelkdijk 464\",\"addressLocality\":\"Schoten\",\"postalCode\":\"2900\",\"addressCountry\":\"BE\"},\"telephone\":\"+32 3 680 13 22\",\"email\":\"info@wirtznv.be\",\"founder\":{\"@type\":\"Person\",\"name\":\"Jacques Wirtz\",\"birthDate\":\"1924\",\"jobTitle\":\"Landscape architect\",\"description\":\"Belgisch tuin- en landschapsarchitect, geboren in Antwerpen in 1924, oprichter van het bureau.\"},\"knowsAbout\":[\"Landscape architecture\",\"Garden design\",\"Public space design\",\"Roof gardens\",\"Private gardens\"],\"areaServed\":[\"BE\",\"NL\",\"FR\",\"DE\",\"GB\",\"US\",\"ES\",\"CH\",\"PL\"],\"foundingDate\":\"1950\",\"employee\":[{\"@type\":\"Person\",\"name\":\"Martin Wirtz\",\"jobTitle\":\"Landscape architect\"},{\"@type\":\"Person\",\"name\":\"Peter Wirtz\",\"jobTitle\":\"Landscape architect\"}],\"location\":[{\"@type\":\"Place\",\"name\":\"Wirtz International Landscape Architects \u2014 Schoten\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Botermelkdijk 464\",\"addressLocality\":\"Schoten\",\"postalCode\":\"2900\",\"addressCountry\":\"BE\"},\"telephone\":\"+32 3 680 13 22\"},{\"@type\":\"Place\",\"name\":\"Wirtz International Landscape Architects \u2014 Hamburg\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Armgartstra\u00dfe 4\",\"addressLocality\":\"Hamburg\",\"postalCode\":\"22087\",\"addressCountry\":\"DE\"},\"telephone\":\"+49 40 226 30336\"},{\"@type\":\"Place\",\"name\":\"Wirtz International Landscape Architects \u2014 Glastonbury\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"100 Western Blvd\",\"addressLocality\":\"Glastonbury\",\"addressRegion\":\"CT\",\"postalCode\":\"06033\",\"addressCountry\":\"US\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wirtznv.com\\\/de\\\/#\\\/schema\\\/person\\\/238ae8b6d8292a0cce4aba73db1f4de7\",\"name\":\"dxv_webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g\",\"caption\":\"dxv_webmaster\"},\"sameAs\":[\"https:\\\/\\\/wirtznv.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chambon Br\u00fcssel | Wirtz International Gartenarchitekten","description":"Chambon in Br\u00fcssel gewann den MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude. Es handelt sich um den gr\u00f6\u00dften Umbau von B\u00fcros in Br\u00fcssel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/","og_locale":"de_DE","og_type":"article","og_title":"Chambon Br\u00fcssel | Wirtz International Gartenarchitekten","og_description":"Chambon in Br\u00fcssel gewann den MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude. Es handelt sich um den gr\u00f6\u00dften Umbau von B\u00fcros in Br\u00fcssel.","og_url":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/","og_site_name":"Wirtz NV","article_published_time":"2017-05-03T09:40:56+00:00","article_modified_time":"2024-05-28T12:44:13+00:00","og_image":[{"width":2000,"height":1124,"url":"https:\/\/wirtznv.com\/wp-content\/uploads\/2017\/05\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg","type":"image\/jpeg"}],"author":"dxv_webmaster","twitter_card":"summary_large_image","twitter_creator":"@Wirtz_Gardens","twitter_site":"@Wirtz_Gardens","twitter_misc":{"Verfasst von":"dxv_webmaster","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/#article","isPartOf":{"@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/"},"author":{"name":"dxv_webmaster","@id":"https:\/\/wirtznv.com\/de\/#\/schema\/person\/238ae8b6d8292a0cce4aba73db1f4de7"},"headline":"Chambon in Br\u00fcssel gewinnt den 27. MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude","datePublished":"2017-05-03T09:40:56+00:00","dateModified":"2024-05-28T12:44:13+00:00","mainEntityOfPage":{"@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/"},"wordCount":258,"publisher":{"@id":"https:\/\/wirtznv.com\/de\/#organization"},"image":{"@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/#primaryimage"},"thumbnailUrl":"https:\/\/wirtznv.com\/wp-content\/uploads\/2017\/05\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/","url":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/","name":"Chambon Br\u00fcssel | Wirtz International Gartenarchitekten","isPartOf":{"@id":"https:\/\/wirtznv.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/#primaryimage"},"image":{"@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/#primaryimage"},"thumbnailUrl":"https:\/\/wirtznv.com\/wp-content\/uploads\/2017\/05\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg","datePublished":"2017-05-03T09:40:56+00:00","dateModified":"2024-05-28T12:44:13+00:00","description":"Chambon in Br\u00fcssel gewann den MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude. Es handelt sich um den gr\u00f6\u00dften Umbau von B\u00fcros in Br\u00fcssel.","breadcrumb":{"@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/#primaryimage","url":"https:\/\/wirtznv.com\/wp-content\/uploads\/2017\/05\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg","contentUrl":"https:\/\/wirtznv.com\/wp-content\/uploads\/2017\/05\/News-Chambon-In-Brussels-Wins-27th-MIPIM-Award-For-Best-Refurbished-Building.jpg","width":2000,"height":1124},{"@type":"BreadcrumbList","@id":"https:\/\/wirtznv.com\/de\/chambon-in-bruessel-gewinnt-den-27-mipim-award-fuer-das-beste-renovierte-gebaeude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wirtznv.com\/de\/"},{"@type":"ListItem","position":2,"name":"Chambon in Br\u00fcssel gewinnt den 27. MIPIM Award f\u00fcr das beste renovierte Geb\u00e4ude"}]},{"@type":"WebSite","@id":"https:\/\/wirtznv.com\/de\/#website","url":"https:\/\/wirtznv.com\/de\/","name":"Wirtz NV","description":"","publisher":{"@id":"https:\/\/wirtznv.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wirtznv.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wirtznv.com\/de\/#organization","name":"Wirtz International Landscape Architects","alternateName":"Wirtz NV","url":"https:\/\/wirtznv.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wirtznv.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wirtznv.com\/wp-content\/uploads\/2021\/03\/logo_header@2x-1.png","contentUrl":"https:\/\/wirtznv.com\/wp-content\/uploads\/2021\/03\/logo_header@2x-1.png","width":177,"height":161,"caption":"Wirtz International Landscape Architects"},"image":{"@id":"https:\/\/wirtznv.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Wirtz_Gardens","https:\/\/www.instagram.com\/Wirtz_International\/"],"description":"Wirtz International Landscape Architects ist ein belgisches Garten- und Landschaftsarchitekturb\u00fcro in Schoten bei Antwerpen, gegr\u00fcndet von Jacques Wirtz. Das B\u00fcro entwirft Privatg\u00e4rten, Firmeng\u00e4rten, \u00f6ffentliche R\u00e4ume und Dachg\u00e4rten im In- und Ausland.","address":{"@type":"PostalAddress","streetAddress":"Botermelkdijk 464","addressLocality":"Schoten","postalCode":"2900","addressCountry":"BE"},"telephone":"+32 3 680 13 22","email":"info@wirtznv.be","founder":{"@type":"Person","name":"Jacques Wirtz","birthDate":"1924","jobTitle":"Landscape architect","description":"Belgisch tuin- en landschapsarchitect, geboren in Antwerpen in 1924, oprichter van het bureau."},"knowsAbout":["Landscape architecture","Garden design","Public space design","Roof gardens","Private gardens"],"areaServed":["BE","NL","FR","DE","GB","US","ES","CH","PL"],"foundingDate":"1950","employee":[{"@type":"Person","name":"Martin Wirtz","jobTitle":"Landscape architect"},{"@type":"Person","name":"Peter Wirtz","jobTitle":"Landscape architect"}],"location":[{"@type":"Place","name":"Wirtz International Landscape Architects \u2014 Schoten","address":{"@type":"PostalAddress","streetAddress":"Botermelkdijk 464","addressLocality":"Schoten","postalCode":"2900","addressCountry":"BE"},"telephone":"+32 3 680 13 22"},{"@type":"Place","name":"Wirtz International Landscape Architects \u2014 Hamburg","address":{"@type":"PostalAddress","streetAddress":"Armgartstra\u00dfe 4","addressLocality":"Hamburg","postalCode":"22087","addressCountry":"DE"},"telephone":"+49 40 226 30336"},{"@type":"Place","name":"Wirtz International Landscape Architects \u2014 Glastonbury","address":{"@type":"PostalAddress","streetAddress":"100 Western Blvd","addressLocality":"Glastonbury","addressRegion":"CT","postalCode":"06033","addressCountry":"US"}}]},{"@type":"Person","@id":"https:\/\/wirtznv.com\/de\/#\/schema\/person\/238ae8b6d8292a0cce4aba73db1f4de7","name":"dxv_webmaster","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ac4d7ab1873815315009d11c27ceb03fab8cfaa9cacc1396d8c439780e46067?s=96&d=mm&r=g","caption":"dxv_webmaster"},"sameAs":["https:\/\/wirtznv.com"]}]}},"_links":{"self":[{"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/posts\/6041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/comments?post=6041"}],"version-history":[{"count":0,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/posts\/6041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/media\/8116"}],"wp:attachment":[{"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/media?parent=6041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/categories?post=6041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wirtznv.com\/de\/wp-json\/wp\/v2\/tags?post=6041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}